{"id":9,"count":0,"description":"Als f\u00fchrender Anbieter von Wechselrichter- und Ladetechnologiel\u00f6sungen hat sich BettSun seit seiner Gr\u00fcndung dem Vorantreiben der globalen gr\u00fcnen Energiewende verschrieben. Das Unternehmen treibt die Innovation und Entwicklung von Energieanwendungstechnologien durch kontinuierliche technologische Weiterentwicklungen voran.","link":"https:\/\/bettsun.com\/de\/kategorie-herunterladen\/video-tutorials\/","name":"Video-Tutorials","slug":"video-tutorials","taxonomy":"download-category","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/bettsun.com\/de\/wp-json\/wp\/v2\/download-category\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bettsun.com\/de\/wp-json\/wp\/v2\/download-category"}],"about":[{"href":"https:\/\/bettsun.com\/de\/wp-json\/wp\/v2\/taxonomies\/download-category"}],"wp:post_type":[{"href":"https:\/\/bettsun.com\/de\/wp-json\/wp\/v2\/download?download-category=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}